{"id":72,"count":1,"description":"","link":"https:\/\/koesterdoel.be\/index.php\/tag\/doelse-feesten\/","name":"Doelse Feesten","slug":"doelse-feesten","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Doelse Feesten Archieven - KoesterDoel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/koesterdoel.be\/index.php\/tag\/doelse-feesten\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Doelse Feesten Archieven - KoesterDoel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/koesterdoel.be\/index.php\/tag\/doelse-feesten\/\" \/>\n<meta property=\"og:site_name\" content=\"KoesterDoel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/tag\\\/doelse-feesten\\\/\",\"url\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/tag\\\/doelse-feesten\\\/\",\"name\":\"Doelse Feesten Archieven - KoesterDoel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/tag\\\/doelse-feesten\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/tag\\\/doelse-feesten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/koesterdoel.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Doelse Feesten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/#website\",\"url\":\"https:\\\/\\\/koesterdoel.be\\\/\",\"name\":\"KoesterDoel\",\"description\":\"Koester Doel\",\"publisher\":{\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/koesterdoel.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/#organization\",\"name\":\"koester Doel\",\"url\":\"https:\\\/\\\/koesterdoel.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/koesterdoel.be\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/koesterdoel_logo@2x-1.png\",\"contentUrl\":\"https:\\\/\\\/koesterdoel.be\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/koesterdoel_logo@2x-1.png\",\"width\":400,\"height\":129,\"caption\":\"koester Doel\"},\"image\":{\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Doelse Feesten Archieven - KoesterDoel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/koesterdoel.be\/index.php\/tag\/doelse-feesten\/","og_locale":"nl_NL","og_type":"article","og_title":"Doelse Feesten Archieven - KoesterDoel","og_url":"https:\/\/koesterdoel.be\/index.php\/tag\/doelse-feesten\/","og_site_name":"KoesterDoel","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/koesterdoel.be\/index.php\/tag\/doelse-feesten\/","url":"https:\/\/koesterdoel.be\/index.php\/tag\/doelse-feesten\/","name":"Doelse Feesten Archieven - KoesterDoel","isPartOf":{"@id":"https:\/\/koesterdoel.be\/#website"},"breadcrumb":{"@id":"https:\/\/koesterdoel.be\/index.php\/tag\/doelse-feesten\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/koesterdoel.be\/index.php\/tag\/doelse-feesten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/koesterdoel.be\/"},{"@type":"ListItem","position":2,"name":"Doelse Feesten"}]},{"@type":"WebSite","@id":"https:\/\/koesterdoel.be\/#website","url":"https:\/\/koesterdoel.be\/","name":"KoesterDoel","description":"Koester Doel","publisher":{"@id":"https:\/\/koesterdoel.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/koesterdoel.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/koesterdoel.be\/#organization","name":"koester Doel","url":"https:\/\/koesterdoel.be\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/koesterdoel.be\/#\/schema\/logo\/image\/","url":"https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/koesterdoel_logo@2x-1.png","contentUrl":"https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/koesterdoel_logo@2x-1.png","width":400,"height":129,"caption":"koester Doel"},"image":{"@id":"https:\/\/koesterdoel.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/koesterdoel.be\/index.php\/wp-json\/wp\/v2\/tags\/72","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/koesterdoel.be\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/koesterdoel.be\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/koesterdoel.be\/index.php\/wp-json\/wp\/v2\/posts?tags=72"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}