{"id":1023,"date":"2021-12-10T11:53:40","date_gmt":"2021-12-10T11:53:40","guid":{"rendered":"https:\/\/koesterdoel.be\/?p=1023"},"modified":"2022-01-15T10:45:41","modified_gmt":"2022-01-15T10:45:41","slug":"brits-monument","status":"publish","type":"post","link":"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/","title":{"rendered":"Brits monument"},"content":{"rendered":"<h3>Brits monument<\/h3>\n<p>Doel werd aan het einde van de Tweede Wereldoorlog relatief laat bevrijd. Op 10 september 1944 waren de Duitsers overal in het Waasland vertrokken behalve in Doel. Zwaarbewapende Duitse achterhoedes vrijwaarden de toegangswegen terwijl zo\u2019n 15.000 Duitse soldaten via Kallo, Kieldrecht en Prosperpolder richting Scheldedorp trokken. Daar werden de schippers en hun schepen opge\u00ebist om de Duitse manschappen over de Schelde te zetten. Hun paarden doolden nog wekenlang doelloos rond in de polder. Achtergelaten munitie wordt tot op de dag van vandaag nog regelmatig aan.getroffen bij graafwerken.<\/p>\n<p>Vanaf eind september 1944 bracht de Britse luchtafweer zijn kanonnen in stelling op de Scheldedijk. Vlak daarna kwamen de sperballons en de zoeklichten. Die moesten Antwerpen en ook het Waasland beschermen tegen de V-bommen die nog maandenlang werden afgevuurd op de Antwerpse Haven.<\/p>\n<figure id=\"attachment_1025\" aria-describedby=\"caption-attachment-1025\" style=\"width: 1024px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-large wp-image-1025\" src=\"https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/afbraakmonument2_Kristof-Pieters-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/afbraakmonument2_Kristof-Pieters-1024x683.jpg 1024w, https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/afbraakmonument2_Kristof-Pieters-300x200.jpg 300w, https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/afbraakmonument2_Kristof-Pieters-768x512.jpg 768w, https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/afbraakmonument2_Kristof-Pieters-600x400.jpg 600w, https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/afbraakmonument2_Kristof-Pieters-800x533.jpg 800w, https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/afbraakmonument2_Kristof-Pieters-227x152.jpg 227w, https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/afbraakmonument2_Kristof-Pieters-143x96.jpg 143w, https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/afbraakmonument2_Kristof-Pieters-585x390.jpg 585w, https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/afbraakmonument2_Kristof-Pieters-385x257.jpg 385w, https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/afbraakmonument2_Kristof-Pieters.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-1025\" class=\"wp-caption-text\">Afbraak Brits monument &#8211; \u00a9 Kristof Pieters<\/figcaption><\/figure>\n<p>Op 20 Juni 1948 werd ter ere van de Britse bevrijders een monument ingewijd in aanwezigheid van de hoog.ste personaliteiten van het land. Het Brits monument werd een nationaal gedenkteken waar elk jaar een herdenking plaatsvond. Het voor Doel emotioneel belangrijke monument werd in 2011 \u2013 kort voor zijn definitieve bescherming \u2013 afgebroken. Na protest werd het teruggeplaatst maar niet op zijn oorspronkelijke plaats. Het staat nu enkele kilometers verder, weggestoken achter de Kerncentrale van Doel. Een bescheiden kruis op de oorspronkelijke plaats herinnert aan het monument.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brits monument Doel werd aan het einde van de Tweede Wereldoorlog relatief laat bevrijd. Op 10 september 1944 waren de Duitsers overal in het Waasland vertrokken behalve in Doel. Zwaarbewapende Duitse achterhoedes vrijwaarden de toegangswegen terwijl zo\u2019n 15.000 Duitse soldaten via Kallo, Kieldrecht en Prosperpolder richting Scheldedorp trokken. Daar werden de schippers en hun schepen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[79],"class_list":["post-1023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-erfgoed-en-bezienswaardigheden","tag-brits-monument"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brits monument - KoesterDoel<\/title>\n<meta name=\"description\" content=\"Doel en Doelpolder hebben alle watersnood- en oorlogs\u00adrampen overleefd. Sinds de jaren zestig van vorige eeuw vormt de uitbreiding van de Antwerpse haven een nieuwe bedreiging. Erfgoed is een mensenrecht. KOESTERDOEL is een eerbetoon aan het werk en het leed van alle generaties Doelenaars en Doelkoesteraars.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brits monument - KoesterDoel\" \/>\n<meta property=\"og:description\" content=\"Doel en Doelpolder hebben alle watersnood- en oorlogs\u00adrampen overleefd. Sinds de jaren zestig van vorige eeuw vormt de uitbreiding van de Antwerpse haven een nieuwe bedreiging. Erfgoed is een mensenrecht. KOESTERDOEL is een eerbetoon aan het werk en het leed van alle generaties Doelenaars en Doelkoesteraars.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/\" \/>\n<meta property=\"og:site_name\" content=\"KoesterDoel\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-10T11:53:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-15T10:45:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/brits-monument.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1795\" \/>\n\t<meta property=\"og:image:height\" content=\"1187\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/2021\\\/12\\\/10\\\/brits-monument\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/2021\\\/12\\\/10\\\/brits-monument\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/#\\\/schema\\\/person\\\/e3af94f7d71f70efbf7a1a4371b01d6c\"},\"headline\":\"Brits monument\",\"datePublished\":\"2021-12-10T11:53:40+00:00\",\"dateModified\":\"2022-01-15T10:45:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/2021\\\/12\\\/10\\\/brits-monument\\\/\"},\"wordCount\":229,\"publisher\":{\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/2021\\\/12\\\/10\\\/brits-monument\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/koesterdoel.be\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/brits-monument.jpg\",\"keywords\":[\"Brits monument\"],\"articleSection\":[\"Erfgoed en bezienswaardigheden\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/2021\\\/12\\\/10\\\/brits-monument\\\/\",\"url\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/2021\\\/12\\\/10\\\/brits-monument\\\/\",\"name\":\"Brits monument - KoesterDoel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/2021\\\/12\\\/10\\\/brits-monument\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/2021\\\/12\\\/10\\\/brits-monument\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/koesterdoel.be\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/brits-monument.jpg\",\"datePublished\":\"2021-12-10T11:53:40+00:00\",\"dateModified\":\"2022-01-15T10:45:41+00:00\",\"description\":\"Doel en Doelpolder hebben alle watersnood- en oorlogs\u00adrampen overleefd. Sinds de jaren zestig van vorige eeuw vormt de uitbreiding van de Antwerpse haven een nieuwe bedreiging. Erfgoed is een mensenrecht. KOESTERDOEL is een eerbetoon aan het werk en het leed van alle generaties Doelenaars en Doelkoesteraars.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/2021\\\/12\\\/10\\\/brits-monument\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/2021\\\/12\\\/10\\\/brits-monument\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/2021\\\/12\\\/10\\\/brits-monument\\\/#primaryimage\",\"url\":\"https:\\\/\\\/koesterdoel.be\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/brits-monument.jpg\",\"contentUrl\":\"https:\\\/\\\/koesterdoel.be\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/brits-monument.jpg\",\"width\":1795,\"height\":1187},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/2021\\\/12\\\/10\\\/brits-monument\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/koesterdoel.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brits monument\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/#website\",\"url\":\"https:\\\/\\\/koesterdoel.be\\\/\",\"name\":\"KoesterDoel\",\"description\":\"Koester Doel\",\"publisher\":{\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/koesterdoel.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/#organization\",\"name\":\"koester Doel\",\"url\":\"https:\\\/\\\/koesterdoel.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/koesterdoel.be\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/koesterdoel_logo@2x-1.png\",\"contentUrl\":\"https:\\\/\\\/koesterdoel.be\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/koesterdoel_logo@2x-1.png\",\"width\":400,\"height\":129,\"caption\":\"koester Doel\"},\"image\":{\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/koesterdoel.be\\\/#\\\/schema\\\/person\\\/e3af94f7d71f70efbf7a1a4371b01d6c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ebbd9057d08eeff85efbf66cc0aa60c09c948bfe45eb5fc89f33a8b93cffffa?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ebbd9057d08eeff85efbf66cc0aa60c09c948bfe45eb5fc89f33a8b93cffffa?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ebbd9057d08eeff85efbf66cc0aa60c09c948bfe45eb5fc89f33a8b93cffffa?s=96&d=blank&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/koesterdoel.be\"],\"url\":\"https:\\\/\\\/koesterdoel.be\\\/index.php\\\/author\\\/pascaltr8430\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brits monument - KoesterDoel","description":"Doel en Doelpolder hebben alle watersnood- en oorlogs\u00adrampen overleefd. Sinds de jaren zestig van vorige eeuw vormt de uitbreiding van de Antwerpse haven een nieuwe bedreiging. Erfgoed is een mensenrecht. KOESTERDOEL is een eerbetoon aan het werk en het leed van alle generaties Doelenaars en Doelkoesteraars.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/","og_locale":"nl_NL","og_type":"article","og_title":"Brits monument - KoesterDoel","og_description":"Doel en Doelpolder hebben alle watersnood- en oorlogs\u00adrampen overleefd. Sinds de jaren zestig van vorige eeuw vormt de uitbreiding van de Antwerpse haven een nieuwe bedreiging. Erfgoed is een mensenrecht. KOESTERDOEL is een eerbetoon aan het werk en het leed van alle generaties Doelenaars en Doelkoesteraars.","og_url":"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/","og_site_name":"KoesterDoel","article_published_time":"2021-12-10T11:53:40+00:00","article_modified_time":"2022-01-15T10:45:41+00:00","og_image":[{"width":1795,"height":1187,"url":"https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/brits-monument.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"admin","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/#article","isPartOf":{"@id":"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/"},"author":{"name":"admin","@id":"https:\/\/koesterdoel.be\/#\/schema\/person\/e3af94f7d71f70efbf7a1a4371b01d6c"},"headline":"Brits monument","datePublished":"2021-12-10T11:53:40+00:00","dateModified":"2022-01-15T10:45:41+00:00","mainEntityOfPage":{"@id":"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/"},"wordCount":229,"publisher":{"@id":"https:\/\/koesterdoel.be\/#organization"},"image":{"@id":"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/#primaryimage"},"thumbnailUrl":"https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/brits-monument.jpg","keywords":["Brits monument"],"articleSection":["Erfgoed en bezienswaardigheden"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/","url":"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/","name":"Brits monument - KoesterDoel","isPartOf":{"@id":"https:\/\/koesterdoel.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/#primaryimage"},"image":{"@id":"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/#primaryimage"},"thumbnailUrl":"https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/brits-monument.jpg","datePublished":"2021-12-10T11:53:40+00:00","dateModified":"2022-01-15T10:45:41+00:00","description":"Doel en Doelpolder hebben alle watersnood- en oorlogs\u00adrampen overleefd. Sinds de jaren zestig van vorige eeuw vormt de uitbreiding van de Antwerpse haven een nieuwe bedreiging. Erfgoed is een mensenrecht. KOESTERDOEL is een eerbetoon aan het werk en het leed van alle generaties Doelenaars en Doelkoesteraars.","breadcrumb":{"@id":"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/#primaryimage","url":"https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/brits-monument.jpg","contentUrl":"https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/brits-monument.jpg","width":1795,"height":1187},{"@type":"BreadcrumbList","@id":"https:\/\/koesterdoel.be\/index.php\/2021\/12\/10\/brits-monument\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/koesterdoel.be\/"},{"@type":"ListItem","position":2,"name":"Brits monument"}]},{"@type":"WebSite","@id":"https:\/\/koesterdoel.be\/#website","url":"https:\/\/koesterdoel.be\/","name":"KoesterDoel","description":"Koester Doel","publisher":{"@id":"https:\/\/koesterdoel.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/koesterdoel.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/koesterdoel.be\/#organization","name":"koester Doel","url":"https:\/\/koesterdoel.be\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/koesterdoel.be\/#\/schema\/logo\/image\/","url":"https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/koesterdoel_logo@2x-1.png","contentUrl":"https:\/\/koesterdoel.be\/wp-content\/uploads\/2021\/12\/koesterdoel_logo@2x-1.png","width":400,"height":129,"caption":"koester Doel"},"image":{"@id":"https:\/\/koesterdoel.be\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/koesterdoel.be\/#\/schema\/person\/e3af94f7d71f70efbf7a1a4371b01d6c","name":"admin","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/8ebbd9057d08eeff85efbf66cc0aa60c09c948bfe45eb5fc89f33a8b93cffffa?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ebbd9057d08eeff85efbf66cc0aa60c09c948bfe45eb5fc89f33a8b93cffffa?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ebbd9057d08eeff85efbf66cc0aa60c09c948bfe45eb5fc89f33a8b93cffffa?s=96&d=blank&r=g","caption":"admin"},"sameAs":["https:\/\/koesterdoel.be"],"url":"https:\/\/koesterdoel.be\/index.php\/author\/pascaltr8430\/"}]}},"_links":{"self":[{"href":"https:\/\/koesterdoel.be\/index.php\/wp-json\/wp\/v2\/posts\/1023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/koesterdoel.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/koesterdoel.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/koesterdoel.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/koesterdoel.be\/index.php\/wp-json\/wp\/v2\/comments?post=1023"}],"version-history":[{"count":0,"href":"https:\/\/koesterdoel.be\/index.php\/wp-json\/wp\/v2\/posts\/1023\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/koesterdoel.be\/index.php\/wp-json\/wp\/v2\/media\/1024"}],"wp:attachment":[{"href":"https:\/\/koesterdoel.be\/index.php\/wp-json\/wp\/v2\/media?parent=1023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/koesterdoel.be\/index.php\/wp-json\/wp\/v2\/categories?post=1023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/koesterdoel.be\/index.php\/wp-json\/wp\/v2\/tags?post=1023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}